{"id":56412,"date":"2026-01-23T11:23:16","date_gmt":"2026-01-23T11:23:16","guid":{"rendered":"https:\/\/www.birkwood.org.uk\/website\/?p=56412"},"modified":"2026-01-23T11:23:16","modified_gmt":"2026-01-23T11:23:16","slug":"mosques-2","status":"publish","type":"post","link":"https:\/\/www.birkwood.org.uk\/website\/mosques-2\/","title":{"rendered":"Mosques"},"content":{"rendered":"<div dir=\"ltr\">We know all about Mosques and their features!<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">\n<div class=\"tiled-gallery type-rectangular tiled-gallery-unresized\" data-original-width=\"1080\" data-carousel-extra='{&quot;blog_id&quot;:1,&quot;permalink&quot;:&quot;https:\\\/\\\/www.birkwood.org.uk\\\/website\\\/mosques-2\\\/&quot;,&quot;likes_blog_id&quot;:49611673}' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 1080px; height: 541px;\" data-original-width=\"1080\" data-original-height=\"541\" > <div class=\"gallery-group images-1\" style=\"width: 720px; height: 541px;\" data-original-width=\"720\" data-original-height=\"541\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.birkwood.org.uk\/website\/mosques-2\/img_2398\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"716\"> <meta itemprop=\"height\" content=\"537\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"56413\" data-orig-file=\"https:\/\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2398.jpeg\" data-orig-size=\"800,600\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_2398\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2398.jpeg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2398.jpeg?fit=720%2C540&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2398.jpeg?w=716&#038;h=537&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2398.jpeg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2398.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2398.jpeg?resize=720%2C540&amp;ssl=1 720w, https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2398.jpeg?resize=768%2C576&amp;ssl=1 768w\" width=\"716\" height=\"537\" loading=\"lazy\" data-original-width=\"716\" data-original-height=\"537\" itemprop=\"http:\/\/schema.org\/image\" title=\"IMG_2398\" alt=\"IMG_2398\" style=\"width: 716px; height: 537px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 360px; height: 541px;\" data-original-width=\"360\" data-original-height=\"541\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.birkwood.org.uk\/website\/mosques-2\/img_2393\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"356\"> <meta itemprop=\"height\" content=\"267\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"56414\" data-orig-file=\"https:\/\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2393.jpeg\" data-orig-size=\"800,600\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_2393\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2393.jpeg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2393.jpeg?fit=720%2C540&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2393.jpeg?w=356&#038;h=267&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2393.jpeg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2393.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2393.jpeg?resize=720%2C540&amp;ssl=1 720w, https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2393.jpeg?resize=768%2C576&amp;ssl=1 768w\" width=\"356\" height=\"267\" loading=\"lazy\" data-original-width=\"356\" data-original-height=\"267\" itemprop=\"http:\/\/schema.org\/image\" title=\"IMG_2393\" alt=\"IMG_2393\" style=\"width: 356px; height: 267px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.birkwood.org.uk\/website\/mosques-2\/img_2404-2\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"356\"> <meta itemprop=\"height\" content=\"266\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"56415\" data-orig-file=\"https:\/\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2404.jpeg\" data-orig-size=\"800,600\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_2404\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2404.jpeg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2404.jpeg?fit=720%2C540&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2404.jpeg?w=356&#038;h=266&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2404.jpeg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2404.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2404.jpeg?resize=720%2C540&amp;ssl=1 720w, https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2404.jpeg?resize=768%2C576&amp;ssl=1 768w\" width=\"356\" height=\"266\" loading=\"lazy\" data-original-width=\"356\" data-original-height=\"266\" itemprop=\"http:\/\/schema.org\/image\" title=\"IMG_2404\" alt=\"IMG_2404\" style=\"width: 356px; height: 266px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 1080px; height: 811px;\" data-original-width=\"1080\" data-original-height=\"811\" > <div class=\"gallery-group images-1\" style=\"width: 1080px; height: 811px;\" data-original-width=\"1080\" data-original-height=\"811\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.birkwood.org.uk\/website\/mosques-2\/img_2403-2\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"1076\"> <meta itemprop=\"height\" content=\"807\"> <img decoding=\"async\" class=\"\" data-attachment-id=\"56416\" data-orig-file=\"https:\/\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2403.jpeg\" data-orig-size=\"800,600\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_2403\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2403.jpeg?fit=300%2C225&#038;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2403.jpeg?fit=720%2C540&#038;ssl=1\" src=\"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2403.jpeg?w=1076&#038;h=807&#038;ssl=1\" srcset=\"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2403.jpeg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2403.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2403.jpeg?resize=720%2C540&amp;ssl=1 720w, https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2403.jpeg?resize=768%2C576&amp;ssl=1 768w\" width=\"1076\" height=\"807\" loading=\"lazy\" data-original-width=\"1076\" data-original-height=\"807\" itemprop=\"http:\/\/schema.org\/image\" title=\"IMG_2403\" alt=\"IMG_2403\" style=\"width: 1076px; height: 807px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>We know all about Mosques and their features!<\/p>\n","protected":false},"author":1,"featured_media":56413,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false,"_links_to":"","_links_to_target":""},"categories":[191,207],"tags":[],"class_list":["post-56412","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-re","category-class-of-2027","et-has-post-format-content","et_post_format-et-post-format-standard"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2398.jpeg?fit=800%2C600&ssl=1","jetpack_shortlink":"https:\/\/wp.me\/p3magh-eFS","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.birkwood.org.uk\/website\/wp-json\/wp\/v2\/posts\/56412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.birkwood.org.uk\/website\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.birkwood.org.uk\/website\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.birkwood.org.uk\/website\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.birkwood.org.uk\/website\/wp-json\/wp\/v2\/comments?post=56412"}],"version-history":[{"count":1,"href":"https:\/\/www.birkwood.org.uk\/website\/wp-json\/wp\/v2\/posts\/56412\/revisions"}],"predecessor-version":[{"id":56417,"href":"https:\/\/www.birkwood.org.uk\/website\/wp-json\/wp\/v2\/posts\/56412\/revisions\/56417"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.birkwood.org.uk\/website\/wp-json\/wp\/v2\/media\/56413"}],"wp:attachment":[{"href":"https:\/\/www.birkwood.org.uk\/website\/wp-json\/wp\/v2\/media?parent=56412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.birkwood.org.uk\/website\/wp-json\/wp\/v2\/categories?post=56412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.birkwood.org.uk\/website\/wp-json\/wp\/v2\/tags?post=56412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}