{"id":58517,"date":"2026-05-06T14:13:24","date_gmt":"2026-05-06T14:13:24","guid":{"rendered":"https:\/\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/05\/Athletics-Lesson-31.jpeg"},"modified":"2026-05-06T14:13:24","modified_gmt":"2026-05-06T14:13:24","slug":"athletics-lesson-31","status":"inherit","type":"attachment","link":"https:\/\/www.birkwood.org.uk\/website\/athletics-lesson-3-2\/athletics-lesson-31\/","title":{"rendered":"Athletics Lesson 31"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_links_to":"","_links_to_target":""},"class_list":["post-58517","attachment","type-attachment","status-inherit","hentry"],"jetpack_shortlink":"https:\/\/wp.me\/a3magh-fdP","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/05\/Athletics-Lesson-31.jpeg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/05\/Athletics-Lesson-31.jpeg?fit=300%2C225&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/05\/Athletics-Lesson-31.jpeg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/05\/Athletics-Lesson-31.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/05\/Athletics-Lesson-31.jpeg?resize=720%2C540&amp;ssl=1 720w, https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/05\/Athletics-Lesson-31.jpeg?resize=768%2C576&amp;ssl=1 768w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-attachment-id=\"58517\" data-permalink=\"https:\/\/www.birkwood.org.uk\/website\/athletics-lesson-3-2\/athletics-lesson-31\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/05\/Athletics-Lesson-31.jpeg?fit=800%2C600&amp;ssl=1\" data-orig-size=\"800,600\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Athletics Lesson 31\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/05\/Athletics-Lesson-31.jpeg?fit=720%2C540&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":800,"height":600,"file":"2026\/05\/Athletics-Lesson-31.jpeg","filesize":128851,"sizes":{"medium":{"file":"Athletics-Lesson-31-300x225.jpeg","width":300,"height":225,"filesize":16796,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/05\/Athletics-Lesson-31.jpeg?fit=300%2C225&ssl=1"},"large":{"file":"Athletics-Lesson-31-720x540.jpeg","width":720,"height":540,"filesize":88589,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/05\/Athletics-Lesson-31.jpeg?fit=720%2C540&ssl=1"},"thumbnail":{"file":"Athletics-Lesson-31-200x200.jpeg","width":200,"height":200,"filesize":10584,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/05\/Athletics-Lesson-31.jpeg?resize=200%2C200&ssl=1"},"medium_large":{"file":"Athletics-Lesson-31-768x576.jpeg","width":768,"height":576,"filesize":99269,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/05\/Athletics-Lesson-31.jpeg?fit=768%2C576&ssl=1"},"et-builder-post-main-image":{"file":"Athletics-Lesson-31-400x250.jpeg","width":400,"height":250,"filesize":27525,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/05\/Athletics-Lesson-31.jpeg?resize=400%2C250&ssl=1"},"et-builder-portfolio-image":{"file":"Athletics-Lesson-31-400x284.jpeg","width":400,"height":284,"filesize":29839,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/05\/Athletics-Lesson-31.jpeg?resize=400%2C284&ssl=1"},"et-builder-gallery-image-portrait":{"file":"Athletics-Lesson-31-400x516.jpeg","width":400,"height":516,"filesize":47591,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/05\/Athletics-Lesson-31.jpeg?resize=400%2C516&ssl=1"},"extra-image-medium":{"file":"Athletics-Lesson-31-627x376.jpeg","width":627,"height":376,"filesize":58211,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/05\/Athletics-Lesson-31.jpeg?resize=627%2C376&ssl=1"},"extra-image-small":{"file":"Athletics-Lesson-31-440x264.jpeg","width":440,"height":264,"filesize":29239,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/05\/Athletics-Lesson-31.jpeg?resize=440%2C264&ssl=1"},"extra-image-square-medium":{"file":"Athletics-Lesson-31-440x440.jpeg","width":440,"height":440,"filesize":44765,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/05\/Athletics-Lesson-31.jpeg?resize=440%2C440&ssl=1"},"extra-image-square-small":{"file":"Athletics-Lesson-31-150x150.jpeg","width":150,"height":150,"filesize":6556,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/05\/Athletics-Lesson-31.jpeg?resize=150%2C150&ssl=1"},"full":{"file":"Athletics-Lesson-31.jpeg?fit=800%2C600&ssl=1","width":800,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/05\/Athletics-Lesson-31.jpeg?fit=800%2C600&ssl=1"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":58516,"source_url":"https:\/\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/05\/Athletics-Lesson-31.jpeg","_links":{"self":[{"href":"https:\/\/www.birkwood.org.uk\/website\/wp-json\/wp\/v2\/media\/58517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.birkwood.org.uk\/website\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.birkwood.org.uk\/website\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.birkwood.org.uk\/website\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.birkwood.org.uk\/website\/wp-json\/wp\/v2\/comments?post=58517"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":58516,"href":"https:\/\/www.birkwood.org.uk\/website\/wp-json\/wp\/v2\/posts\/58516"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}