{"id":56407,"date":"2026-01-23T11:21:01","date_gmt":"2026-01-23T11:21:01","guid":{"rendered":"https:\/\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2359.jpeg"},"modified":"2026-01-23T11:21:01","modified_gmt":"2026-01-23T11:21:01","slug":"img_2359","status":"inherit","type":"attachment","link":"https:\/\/www.birkwood.org.uk\/website\/fish-2\/img_2359\/","title":{"rendered":"IMG_2359"},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","_links_to":"","_links_to_target":""},"class_list":["post-56407","attachment","type-attachment","status-inherit","hentry"],"jetpack_shortlink":"https:\/\/wp.me\/a3magh-eFN","jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2359.jpeg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2359.jpeg?fit=300%2C225&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2359.jpeg?w=800&amp;ssl=1 800w, https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2359.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2359.jpeg?resize=720%2C540&amp;ssl=1 720w, https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2359.jpeg?resize=768%2C576&amp;ssl=1 768w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-attachment-id=\"56407\" data-permalink=\"https:\/\/www.birkwood.org.uk\/website\/fish-2\/img_2359\/\" data-orig-file=\"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2359.jpeg?fit=800%2C600&amp;ssl=1\" data-orig-size=\"800,600\" data-comments-opened=\"0\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"IMG_2359\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2359.jpeg?fit=720%2C540&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":800,"height":600,"file":"2026\/01\/IMG_2359.jpeg","filesize":69341,"sizes":{"medium":{"file":"IMG_2359-300x225.jpeg","width":300,"height":225,"filesize":14245,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2359.jpeg?fit=300%2C225&ssl=1"},"large":{"file":"IMG_2359-720x540.jpeg","width":720,"height":540,"filesize":53739,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2359.jpeg?fit=720%2C540&ssl=1"},"thumbnail":{"file":"IMG_2359-200x200.jpeg","width":200,"height":200,"filesize":9471,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2359.jpeg?resize=200%2C200&ssl=1"},"medium_large":{"file":"IMG_2359-768x576.jpeg","width":768,"height":576,"filesize":58883,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2359.jpeg?fit=768%2C576&ssl=1"},"et-builder-post-main-image":{"file":"IMG_2359-400x250.jpeg","width":400,"height":250,"filesize":19384,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2359.jpeg?resize=400%2C250&ssl=1"},"et-builder-portfolio-image":{"file":"IMG_2359-400x284.jpeg","width":400,"height":284,"filesize":21298,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2359.jpeg?resize=400%2C284&ssl=1"},"et-builder-gallery-image-portrait":{"file":"IMG_2359-400x516.jpeg","width":400,"height":516,"filesize":28866,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2359.jpeg?resize=400%2C516&ssl=1"},"extra-image-medium":{"file":"IMG_2359-627x376.jpeg","width":627,"height":376,"filesize":35765,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2359.jpeg?resize=627%2C376&ssl=1"},"extra-image-small":{"file":"IMG_2359-440x264.jpeg","width":440,"height":264,"filesize":20613,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2359.jpeg?resize=440%2C264&ssl=1"},"extra-image-square-medium":{"file":"IMG_2359-440x440.jpeg","width":440,"height":440,"filesize":29911,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2359.jpeg?resize=440%2C440&ssl=1"},"extra-image-square-small":{"file":"IMG_2359-150x150.jpeg","width":150,"height":150,"filesize":6400,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2359.jpeg?resize=150%2C150&ssl=1"},"full":{"file":"IMG_2359.jpeg?fit=800%2C600&ssl=1","width":800,"height":600,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2359.jpeg?fit=800%2C600&ssl=1"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":56406,"source_url":"https:\/\/www.birkwood.org.uk\/website\/wp-content\/uploads\/2026\/01\/IMG_2359.jpeg","filename":"IMG_2359.jpeg","filesize":69341,"_links":{"self":[{"href":"https:\/\/www.birkwood.org.uk\/website\/wp-json\/wp\/v2\/media\/56407","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.birkwood.org.uk\/website\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.birkwood.org.uk\/website\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.birkwood.org.uk\/website\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.birkwood.org.uk\/website\/wp-json\/wp\/v2\/comments?post=56407"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":56406,"href":"https:\/\/www.birkwood.org.uk\/website\/wp-json\/wp\/v2\/posts\/56406"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}